{"id":3982,"date":"2021-08-30T15:47:32","date_gmt":"2021-08-30T13:47:32","guid":{"rendered":"https:\/\/www.educazionedigitale.it\/dolcescuolacameo\/?page_id=3982"},"modified":"2021-10-11T08:42:29","modified_gmt":"2021-10-11T06:42:29","slug":"contenuti-dolce-scuola","status":"publish","type":"page","link":"https:\/\/www.educazionedigitale.it\/dolcescuolacameo\/contenuti-dolce-scuola\/","title":{"rendered":"Contenuti"},"content":{"rendered":"\n  <div class=\"banner has-hover banner-home\" id=\"banner-1748333696\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <img loading=\"lazy\" decoding=\"async\" width=\"1020\" height=\"172\" src=\"https:\/\/www.educazionedigitale.it\/dolcescuolacameo\/wp-content\/uploads\/2020\/10\/strun-1024x173.jpg\" class=\"bg attachment-large size-large\" alt=\"\" \/>                                    \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n   <div id=\"text-box-510569622\" class=\"text-box banner-layer x10 md-x10 lg-x10 y50 md-y50 lg-y50 res-text\">\n                     <div data-animate=\"fadeInLeft\">           <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-left\">\n                  \n              <\/div>\n           <\/div>\n       <\/div>                     \n<style>\n#text-box-510569622 {\n  width: 60%;\n}\n#text-box-510569622 .text-box-content {\n  font-size: 100%;\n}\n@media (min-width:550px) {\n  #text-box-510569622 {\n    width: 100%;\n  }\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-1748333696 {\n  padding-top: 260px;\n}\n<\/style>\n  <\/div>\n\n\n<div class=\"row\"  id=\"row-1299199134\">\n\t<div id=\"gap-825197894\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-825197894 {\n  padding-top: 20px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t<div id=\"col-987600680\" class=\"col large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<div class=\"big-title\" style=\" padding-bottom:10px;\"><strong><strong>La scintilla che accende la curiosit\u00e0<\/strong>.<\/strong><\/div>\n<div style=\"height:2px; width:100%; background:#364294\"><\/div>\n\t<div id=\"gap-110486415\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-110486415 {\n  padding-top: 20px;\n}\n<\/style>\n\t<\/div>\n\t\n<p style=\"text-align:justify\">\u201c<strong>Dolce Scuola cameo. Educare facendo<\/strong>\u201d vuole essere la scintilla che accende nei bambini la voglia di conoscere sperimentando, e la alimenta ogni giorno supportando gli insegnanti con contenuti pratici, integrati e aggiornati per creare una generazione che concepisca il cibo come relazione e stabilisca con esso un rapporto sostenibile. <\/p>\n<p style=\"text-align:justify\">\u00c8 nella dimensione del fare che si concretizza il contributo educativo di cameo. Il programma spinge i bambini a provare, sperimentare, mettersi in gioco, li stimola all\u2019esperienza e li incentiva alla costruzione, in prima persona, di un rapporto consapevole con la dimensione del cibo.<\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n<div class=\"row\"  id=\"row-1958117437\">\n\n\t<div id=\"col-1796387182\" class=\"col large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<div class=\"big-title\" style=\" padding-bottom:10px; line-height:1.3\"><strong><strong>\u201cCON MUU MUU A SCUOLA DI ALIMENTAZIONE\u201d<br \/> e \u201cLA FARINA DEL MIO SACCO\u201d: i due percorsi <br \/>per le scuole primarie e dell&#8217;infanzia.<\/strong><\/strong><\/div>\n<div style=\"height:2px; width:100%; background:#364294\"><\/div>\n\t<div id=\"gap-1224919434\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1224919434 {\n  padding-top: 20px;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1461712200\" class=\"col large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<p style=\"text-align:justify\">\u201c<strong>Dolce Scuola cameo. Educare facendo<\/strong>\u201d \u00e8 costituito da due percorsi distinti per le scuole primarie e dell\u2019infanzia.<\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-830926348\" class=\"col large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<div class=\"row align-middle align-center\"  id=\"row-1484310494\">\n\n\t<div id=\"col-458472862\" class=\"col medium-5 small-12 large-5\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_2086810721\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1019\" height=\"488\" src=\"https:\/\/www.educazionedigitale.it\/dolcescuolacameo\/wp-content\/uploads\/2021\/09\/5.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.educazionedigitale.it\/dolcescuolacameo\/wp-content\/uploads\/2021\/09\/5.png 1019w, https:\/\/www.educazionedigitale.it\/dolcescuolacameo\/wp-content\/uploads\/2021\/09\/5-300x144.png 300w, https:\/\/www.educazionedigitale.it\/dolcescuolacameo\/wp-content\/uploads\/2021\/09\/5-768x368.png 768w\" sizes=\"auto, (max-width: 1019px) 100vw, 1019px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_2086810721 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1314242941\" class=\"col medium-7 small-12 large-7\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<p style=\"text-align: justify;\">Il primo \u00e8 \u201c<strong>Con Muu Muu a scuola di alimentazione<\/strong>\u201d che cura vari aspetti della nutrizione, dalla conoscenza del cibo all\u2019igiene e sicurezza, da un approccio culturale ad uno sensoriale fino a quello scientifico.<\/p>\n<p style=\"text-align: justify; margin-bottom: 0px;\">Per scoprire il percorso <em><strong><a href=\"https:\/\/www.educazionedigitale.it\/dolcescuolacameo\/con-muu-muu-a-scuola\/\" target=\"_blank\" rel=\"noopener\" style=\"color:blue\"><u>clicca qui<\/u><\/a><\/strong><\/em>.<\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n<div class=\"row align-middle align-center\"  id=\"row-306483948\">\n\n\t<div id=\"col-265205469\" class=\"col medium-7 small-12 large-7\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<p style=\"text-align:justify\"> Il secondo \u00e8 \u201c<strong>La Farina del mio sacco. Il ruolo del cibo come facilitatore di relazioni positive<\/strong>\u201d che intende stimolare i bambini a pensare al cibo come relazione e a vivere in prima persona tutti gli aspetti emotivi che ruotano intorno alla preparazione di un dolce.<\/p>\n<p style=\"text-align: justify; margin-bottom: 0px;\">Per scoprire il percorso <em><strong><a href=\"\/\/www.educazionedigitale.it\/dolcescuolacameo\/la-farina-del-mio-sacco\/\" target=\"_blank\" rel=\"noopener\" style=\"color:blue\"><u>clicca qui<\/u><\/a><\/strong><\/em>.<\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-32663181\" class=\"col medium-5 small-12 large-5\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1224998418\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1019\" height=\"488\" src=\"https:\/\/www.educazionedigitale.it\/dolcescuolacameo\/wp-content\/uploads\/2021\/09\/6.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.educazionedigitale.it\/dolcescuolacameo\/wp-content\/uploads\/2021\/09\/6.png 1019w, https:\/\/www.educazionedigitale.it\/dolcescuolacameo\/wp-content\/uploads\/2021\/09\/6-300x144.png 300w, https:\/\/www.educazionedigitale.it\/dolcescuolacameo\/wp-content\/uploads\/2021\/09\/6-768x368.png 768w\" sizes=\"auto, (max-width: 1019px) 100vw, 1019px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1224998418 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-32663181 > .col-inner {\n  margin: -10px 0px 0px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\t<div id=\"gap-1220570334\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1220570334 {\n  padding-top: 17px;\n}\n<\/style>\n\t<\/div>\n\t\n<p style=\"text-align:justify\">Entrambi i progetti forniscono materiali utili per una sperimentazione concreta della dimensione del fare: gli insegnanti hanno a disposizione manuali d\u2019uso, strumenti multimediali e video con cui coinvolgere i propri alunni. I bambini sono guidati e incoraggiati alla conoscenza attraverso l\u2019esperienza diretta e mettendo \u201cle mani in pasta\u201d.<\/p>\n<p style=\"text-align:justify\">Perch\u00e9 \u00e8 proprio tramite l\u2019esperienza che cameo vuole piantare nei pi\u00f9 piccoli i semi di un rapporto consapevole e sostenibile con il cibo, per iniziare a coltivare, oggi, le abitudini virtuose di domani.<\/p>\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-830926348 > .col-inner {\n  margin: -28px 0px 0px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_2047871539\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner image-cover dark\" style=\"padding-top:232px;margin:-47px 0px 0px 0px;\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"344\" src=\"https:\/\/www.educazionedigitale.it\/dolcescuolacameo\/wp-content\/uploads\/2021\/08\/cameobasepag-1.png\" class=\"attachment-original size-original\" alt=\"\" srcset=\"https:\/\/www.educazionedigitale.it\/dolcescuolacameo\/wp-content\/uploads\/2021\/08\/cameobasepag-1.png 1920w, https:\/\/www.educazionedigitale.it\/dolcescuolacameo\/wp-content\/uploads\/2021\/08\/cameobasepag-1-300x54.png 300w, https:\/\/www.educazionedigitale.it\/dolcescuolacameo\/wp-content\/uploads\/2021\/08\/cameobasepag-1-1024x183.png 1024w, https:\/\/www.educazionedigitale.it\/dolcescuolacameo\/wp-content\/uploads\/2021\/08\/cameobasepag-1-768x138.png 768w, https:\/\/www.educazionedigitale.it\/dolcescuolacameo\/wp-content\/uploads\/2021\/08\/cameobasepag-1-1536x275.png 1536w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_2047871539 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":6,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-blank.php","meta":{"_monsterinsights_skip_tracking":false,"footnotes":"","_members_access_role":[],"_members_access_error":""},"class_list":["post-3982","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Contenuti - Dolce Scuola Cameo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.educazionedigitale.it\/dolcescuolacameo\/contenuti-dolce-scuola\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Contenuti - Dolce Scuola Cameo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.educazionedigitale.it\/dolcescuolacameo\/contenuti-dolce-scuola\/\" \/>\n<meta property=\"og:site_name\" content=\"Dolce Scuola Cameo\" \/>\n<meta property=\"article:modified_time\" content=\"2021-10-11T06:42:29+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.educazionedigitale.it\\\/dolcescuolacameo\\\/contenuti-dolce-scuola\\\/\",\"url\":\"https:\\\/\\\/www.educazionedigitale.it\\\/dolcescuolacameo\\\/contenuti-dolce-scuola\\\/\",\"name\":\"Contenuti - Dolce Scuola Cameo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.educazionedigitale.it\\\/dolcescuolacameo\\\/#website\"},\"datePublished\":\"2021-08-30T13:47:32+00:00\",\"dateModified\":\"2021-10-11T06:42:29+00:00\",\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.educazionedigitale.it\\\/dolcescuolacameo\\\/contenuti-dolce-scuola\\\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.educazionedigitale.it\\\/dolcescuolacameo\\\/#website\",\"url\":\"https:\\\/\\\/www.educazionedigitale.it\\\/dolcescuolacameo\\\/\",\"name\":\"Dolce Scuola Cameo\",\"description\":\"La dolcezza creata dalle nostre mani\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.educazionedigitale.it\\\/dolcescuolacameo\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Contenuti - Dolce Scuola Cameo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.educazionedigitale.it\/dolcescuolacameo\/contenuti-dolce-scuola\/","og_locale":"it_IT","og_type":"article","og_title":"Contenuti - Dolce Scuola Cameo","og_url":"https:\/\/www.educazionedigitale.it\/dolcescuolacameo\/contenuti-dolce-scuola\/","og_site_name":"Dolce Scuola Cameo","article_modified_time":"2021-10-11T06:42:29+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.educazionedigitale.it\/dolcescuolacameo\/contenuti-dolce-scuola\/","url":"https:\/\/www.educazionedigitale.it\/dolcescuolacameo\/contenuti-dolce-scuola\/","name":"Contenuti - Dolce Scuola Cameo","isPartOf":{"@id":"https:\/\/www.educazionedigitale.it\/dolcescuolacameo\/#website"},"datePublished":"2021-08-30T13:47:32+00:00","dateModified":"2021-10-11T06:42:29+00:00","inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.educazionedigitale.it\/dolcescuolacameo\/contenuti-dolce-scuola\/"]}]},{"@type":"WebSite","@id":"https:\/\/www.educazionedigitale.it\/dolcescuolacameo\/#website","url":"https:\/\/www.educazionedigitale.it\/dolcescuolacameo\/","name":"Dolce Scuola Cameo","description":"La dolcezza creata dalle nostre mani","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.educazionedigitale.it\/dolcescuolacameo\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/www.educazionedigitale.it\/dolcescuolacameo\/wp-json\/wp\/v2\/pages\/3982","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.educazionedigitale.it\/dolcescuolacameo\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.educazionedigitale.it\/dolcescuolacameo\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.educazionedigitale.it\/dolcescuolacameo\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.educazionedigitale.it\/dolcescuolacameo\/wp-json\/wp\/v2\/comments?post=3982"}],"version-history":[{"count":3,"href":"https:\/\/www.educazionedigitale.it\/dolcescuolacameo\/wp-json\/wp\/v2\/pages\/3982\/revisions"}],"predecessor-version":[{"id":4093,"href":"https:\/\/www.educazionedigitale.it\/dolcescuolacameo\/wp-json\/wp\/v2\/pages\/3982\/revisions\/4093"}],"wp:attachment":[{"href":"https:\/\/www.educazionedigitale.it\/dolcescuolacameo\/wp-json\/wp\/v2\/media?parent=3982"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}