{"id":308,"date":"2015-03-11T16:26:27","date_gmt":"2015-03-11T15:26:27","guid":{"rendered":"http:\/\/www.educazionedigitale.it\/unipolpcto\/?page_id=308"},"modified":"2022-12-12T18:07:38","modified_gmt":"2022-12-12T17:07:38","slug":"recupero-credenziali","status":"publish","type":"page","link":"https:\/\/www.educazionedigitale.it\/unipolpcto\/recupero-credenziali\/","title":{"rendered":"Recupero credenziali"},"content":{"rendered":"<div class=\"container section-title-container title\" style=\"margin-bottom:-25px;max-width:100%;\"><h2 class=\"section-title section-title-center\"><b aria-hidden=\"true\"><\/b><span class=\"section-title-main\" style=\"font-size:65%;color:rgb(15, 50, 80);\">Recupero credenziali<\/span><b aria-hidden=\"true\"><\/b><\/h2><\/div>\n\t<div id=\"gap-1323551294\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1323551294 {\n  padding-top: 20px;\n}\n<\/style>\n\t<\/div>\n\t\n\n        <!DOCTYPE html PUBLIC \"-\/\/W3C\/\/DTD XHTML 1.0 Transitional\/\/EN\" \"https:\/\/www.w3.org\/TR\/xhtml1\/DTD\/xhtml1-transitional.dtd\">\n        <html xmlns=\"https:\/\/www.w3.org\/1999\/xhtml\" xml:lang=\"it-it\" lang=\"it-it\" class=\"chrome chrome36\"><head><meta http-equiv=\"Content-Type\" content=\"text\/html; charset=UTF-8\">\n            <title>Password smarrita? - Educazione Digitale<\/title>\n            <!--<link rel=\"stylesheet\" href=\"https:\/\/www.educazionedigitale.it\/php-custom\/css\/recuperocredenziali\/djfappend.css\" type=\"text\/css\">\n            <link rel=\"stylesheet\" href=\"https:\/\/www.educazionedigitale.it\/php-custom\/css\/recuperocredenziali\/highslide.css\" type=\"text\/css\">\n            <link rel=\"stylesheet\" href=\"https:\/\/www.educazionedigitale.it\/php-custom\/css\/recuperocredenziali\/template.css\" type=\"text\/css\">\n            <link rel=\"stylesheet\" href=\"https:\/\/www.educazionedigitale.it\/php-custom\/recuperocredenziali\/csssystem.css\" type=\"text\/css\">\n            <link rel=\"stylesheet\" href=\"https:\/\/www.educazionedigitale.it\/php-custom\/recuperocredenziali\/cssgeneral.css\" type=\"text\/css\">-->\n\n            <script>\n                var path_principale = 'https:\/\/www.educazionedigitale.it\/unipolpcto\/';\n                var path_totale = 'https:\/\/www.educazionedigitale.it\/php-custom\/';\n                var percorso_corrente = 179;\n                var directory = 'unipolpcto';\n            <\/script>\n            <script type=\"text\/javascript\" src=\"https:\/\/www.educazionedigitale.it\/php-custom\/js\/actions-recupero.js\"><\/script>\n            <script type=\"text\/javascript\" src=\"https:\/\/www.educazionedigitale.it\/php-custom\/language\/it.js\"><\/script>\n\n        <\/head>\n\n        <body onLoad=\"init('it');\">\n\n        <div id=\"error-info\" style=\"display:none;font-size:8px;color:#eee;width:100%;border-bottom:1px solid #eee;margin-bottom:10px\">https:\/\/www.educazionedigitale.it\/unipolpcto\/<\/div>\n\n                    <div>\n\n                <h4>\n                                            Hai dimenticato il Nome utente o la Password?\n                                    <\/h4>\n\n                <hr \/>\n\n                <form method=\"post\" action=\"https:\/\/www.educazionedigitale.it\/unipolpcto\/wp-json\/wp\/v2\/pages\/308\" class=\"cb_form\" id=\"adminForm\" name=\"adminForm\">\n\n                    <div class=\"cb_form_instructions\">\n\n                        <p id=\"cb_lost_password\" style=\"text-align:justify;\">\n                                                            Inserisci il tuo <b>indirizzo email<\/b>, e clicca su <b>INVIA<\/b>. Ti invieremo una email con il tuo username e una nuova password per accedere alla piattaforma.<br \/>\n                                Se non ti dovesse arrivare la email, ti consigliamo di controllare la cartella <b>spam<\/b>.\n                                                    <\/p>\n\n                    <\/div>\n\n                    <div id=\"cb_step1_form\" style=\"display:block;\">\n\n                        <div  id=\"cb_line_checkemail\">\n                            <label for=\"checkemail\">Email:<\/label>\n                            <div class=\"cb_field\">\n                                <div>\n                                    <input type=\"text\" name=\"email\" id=\"email\" class=\"inputbox\" size=\"30\" maxlength=\"255\" onChange=\"checkEmail();\" style=\"margin-bottom:0px;\">\n                                    <input type=\"hidden\" name=\"emailchecked\" id=\"emailchecked\" value=\"0\">\n                                    <div id=\"email_comm\"><\/div>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n\n                        <div  id=\"cb_line_lostbutton\">\n                            <script>\n                                document.getElementById('cb_line_lostbutton').style.display = 'none';\n                            <\/script>\n                            <span class=\"art-button-wrapper\">\n                                <span class=\"art-button-r\">\n                                    <input type=\"button\" class=\"button primary custom-green\" style=\"border:none;margin-top:20px;\" id=\"cbsendnewuspass\" value=\"INVIA\" onClick=\"checkInvio()\">\n                                <\/span>\n                            <\/span>\n                        <\/div>\n\n                    <\/div>\n\n                    <input type=\"hidden\" name=\"act\" id=\"act\" value=\"invio-pass\"\/>\n\n                <\/form>\n\n            <\/div>\n                <\/body>\n        <\/html>\n    \n\t<div id=\"gap-1700955228\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1700955228 {\n  padding-top: 300px;\n}\n<\/style>\n\t<\/div>\n\t\n","protected":false},"excerpt":{"rendered":"\t<div id=\"gap-782757094\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-782757094 {\n  padding-top: 55px;\n}\n@media (min-width:550px) {\n  #gap-782757094 {\n    padding-top: 90px;\n  }\n}\n@media (min-width:850px) {\n  #gap-782757094 {\n    padding-top: 120px;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n\n  <div class=\"banner has-hover banner-home\" id=\"banner-583243669\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <img width=\"2560\" height=\"1707\" src=\"https:\/\/www.educazionedigitale.it\/unipolpcto\/wp-content\/uploads\/2022\/12\/study-together-is-fun-teamwork-team-building-concept-four-happy-students-are-sitting-near-college-building-holding-books-devices-wearing-casual-smart-smiling-nice-summer-scaled.jpg\" class=\"bg attachment-original size-original\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/>                                    \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n   <div id=\"text-box-1832369413\" class=\"text-box banner-layer x50 md-x50 lg-x50 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-1832369413 {\n  width: 60%;\n}\n#text-box-1832369413 .text-box-content {\n  font-size: 100%;\n}\n@media (min-width:550px) {\n  #text-box-1832369413 {\n    width: 60%;\n  }\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-583243669 {\n  padding-top: 250px;\n}\n#banner-583243669 .banner-bg img {\n  object-position: 0% 23%;\n}\n<\/style>\n  <\/div>\n\n\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_monsterinsights_skip_tracking":false,"footnotes":"","_members_access_role":[],"_members_access_error":""},"class_list":["post-308","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.educazionedigitale.it\/unipolpcto\/wp-json\/wp\/v2\/pages\/308","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.educazionedigitale.it\/unipolpcto\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.educazionedigitale.it\/unipolpcto\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.educazionedigitale.it\/unipolpcto\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.educazionedigitale.it\/unipolpcto\/wp-json\/wp\/v2\/comments?post=308"}],"version-history":[{"count":3,"href":"https:\/\/www.educazionedigitale.it\/unipolpcto\/wp-json\/wp\/v2\/pages\/308\/revisions"}],"predecessor-version":[{"id":5656,"href":"https:\/\/www.educazionedigitale.it\/unipolpcto\/wp-json\/wp\/v2\/pages\/308\/revisions\/5656"}],"wp:attachment":[{"href":"https:\/\/www.educazionedigitale.it\/unipolpcto\/wp-json\/wp\/v2\/media?parent=308"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}